{"id":511,"date":"2019-06-04T06:02:34","date_gmt":"2019-06-04T04:02:34","guid":{"rendered":"http:\/\/pilarsantfrancesc.es\/val\/?page_id=511"},"modified":"2026-01-16T14:01:55","modified_gmt":"2026-01-16T13:01:55","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/pilarsantfrancesc.es\/val\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"\n<p style=\"text-align:justify\">En compliment en lo dispost en l&#8217;art\u00edcul 22.2 de la Llei 34\/2002, d&#8217;11 de juliol, de Servicis de la Societat de l&#8217;Informaci\u00f3 i de Comer\u00e7 Electr\u00f2nic, L&#8217;AGRUPACI\u00d3 EL PILAR SANT FRANCESC (en avant, el &#8220;TITULAR&#8221;), l&#8217;informa de que pot recopilar informaci\u00f3 sobre els h\u00e0bits de b\u00fasqueda dels usuaris de la web per mig de cookies o archius de registre. No s&#8217;utilisaran les cookies per a arreplegar informaci\u00f3 de car\u00e0cter personal. Solament s&#8217;instalaran si l&#8217;USUARI permaneix i continua navegant en nostra p\u00e0gina web, <a href=\"https:\/\/pilarsantfrancesc.es\/val\/wp-content\/uploads\/sites\/2\/2026\/02\/Triador-scaled-1.jpg\">https:\/\/pilarsantfrancesc.es\/val<\/a> (en avant, &#8220;LA WEB&#8221;), entenent que consentix el seu us i instalaci\u00f3. A continuaci\u00f3, proporcionem informaci\u00f3 detallada sobre qu\u00e9 \u00e9s una cookie, per a qu\u00e9 servix, quins tipos de cookies utilisem, quines s\u00f3n les seues finalitats i c\u00f3m pot configurar-les o deshabilitar-les si aixina ho desija.<br><br>\n\nEsta pol\u00edtica de cookies va ser actualisada per \u00faltima volta el 14 de decembre de 2022 i s&#8217;aplica als ciutadans i residents llegals permanents de l&#8217;Espai Econ\u00f2mic Europeu i Su\u00efssa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">1. \u00bfQu\u00e9 s\u00f3n les cookies?<\/h4>\n\n\n\n<p style=\"text-align:justify\">Una cookie \u00e9s un menut archiu que s&#8217;envia junt en les p\u00e0gines d&#8217;esta web i que el seu navegador almagasena en el disc dur del seu ordenador u atre dispositiu. L&#8217;informaci\u00f3 almagasenada pot ser tornada als nostres servidors o als servidors de tercers apropiats durant una visita posterior.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">2. \u00bfQu\u00e9 s\u00f3n els scripts?<\/h4>\n\n\n\n<p style=\"text-align:justify\">Un script \u00e9s un fragment de c\u00f2dic de programa que s&#8217;utilisa per a fer que la nostra web funcione correctament i de forma interactiva. Este c\u00f2dic s&#8217;eixecuta en el nostre servidor o en el seu dispositiu.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">3. \u00bfQu\u00e9 \u00e9s un web beacon?<\/h4>\n\n\n\n<p style=\"text-align:justify\">Una baliza web (o una etiqueta de p\u00edxel) \u00e9s una menuda i invisible pe\u00e7a de text o image en una web que s&#8217;utilisa per a monitorear el tr\u00e0fic en una web. Per a aix\u00f2, s&#8217;almagasenen v\u00e0ries senyes sobre vost\u00e9 per mig d&#8217;estes balices web.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4. Tipos de cookies utilisades<\/h4>\n\n\n\n<p style=\"text-align:jusfity\">LA WEB <a href=\"https:\/\/pilarsantfrancesc.es\/val\">https:\/\/pilarsantfrancesc.es\/val<\/a> utilisa els seg\u00fcents tipos de cookies:<\/p>\n\n\n\n<ul style=\"text-align:justify\"><li><strong>Cookies t\u00e8cniques o funcionals:<\/strong> Algunes cookies asseguren que certes parts de LA WEB funcionen correctament i que les seues prefer\u00e8ncies d&#8217;usuari seguixquen recordant-li. En colocar cookies funcionals, li facilitem la visita LA WEB. D&#8217;esta manera, no necessita introduir repetidament la mateixa informaci\u00f3 quan visita LA WEB i, per eixemple, els art\u00edculs permaneixen en la seua cistella de la compra fins que haja pagat. Podem colocar estes cookies sense el seu consentiment.<\/li><li><strong>Cookies d&#8217;estad\u00edstiques:<\/strong> Utilisem cookies estad\u00edstiques per a optimisar l&#8217;experi\u00e8ncia de LA WEB per als nostres usuaris. En estes cookies estad\u00edstiques obtenim informaci\u00f3 sobre l&#8217;us de la LA WEB. Li demanem el seu perm\u00eds per a colocar cookies d&#8217;estad\u00edstiques.<\/li><li><strong>Cookies de Marketing\/Seguiment:<\/strong> Las cookies de markeging\/seguiment s\u00f3n cookies, o qualsevol atra forma d&#8217;almagasenament local, usades per a crear perfils d&#8217;usuari per a mostrar publicitat o per a fer el seguiment de l&#8217;usuari en esta web o en v\u00e0ries web en fins de m\u00e0rqueting similars.<\/li><li><strong>Rets socials:<\/strong> En la nostra web hem incl\u00f3s contingut de Facebook, Twitter, WhatsApp i Instagram per a promoure p\u00e0gines web (p.ej.: \u00abM&#8217;agrada\u00bb, \u00abPinear\u00bb) o compartir (p.ej.: \u00abtuitear\u00bb) en rets socials com Facebook, Twitter, WhatsApp i Instagram. Este contingut est\u00e0 incrustat en c\u00f2dic derivat de Facebook, Twitter, WhatsApp i Instagram i guarda cookies. Este contingut podria processar certa informaci\u00f3 per a anuncis personalisats.<br>Per favor, lligga la pol\u00edtica de privacitat d&#8217;estes rets socials (que pot canviar freq\u00fcentment) per a saber que fan en les seues senyes (personals) que processen usant estes cookies. Les senyes que reben s\u00f3n anonimisades lo m\u00e0xim possible. Facebook, Twitter, WhatsApp i Instagram estan ubicats en els Estats Units.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">5. Cookies utilisades<\/h4>\n\n\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>OptinMonster<\/h3> <p>Estad\u00edsticas<\/p> <label for=\"cmplz_service_optinmonster\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service optinmonster<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos OptinMonster para mailing list subscriptions. <a href=\"https:\/\/cookiedatabase.org\/service\/optinmonster\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Estos datos no se comparten con terceros.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/optinmonster\/omvisits\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">omVisits<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar el n\u00famero de visitas<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/optinmonster\/omvisitsfirst\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">omVisitsFirst<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar un ID de usuario \u00fanico<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/optinmonster\/omsessionstart\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">omSessionStart<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar hora de visita<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/optinmonster\/omsessionpageviews\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">omSessionPageviews<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Contar y rastrear p\u00e1ginas vistas<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>TUS (Resumable File Transfer)<\/h3> <p>Funcional<\/p> <label for=\"cmplz_service_tus-(resumable-file-transfer)\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service tus-(resumable-file-transfer)<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p> <a href=\"https:\/\/cookiedatabase.org\/service\/tus-resumable-file-transfer\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Estos datos no se comparten con terceros.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tus-resumable-file-transfer\/tussupport\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">tusSupport<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Read if resumable file transfer is supported<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Google reCAPTCHA<\/h3> <p>Funcional<\/p> <label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Google reCAPTCHA para spam prevention. <a href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de Google reCAPTCHA<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/_grecaptcha\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">_grecaptcha<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar protecci\u00f3n contra correo no deseado<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Complianz<\/h3> <p>Funcional<\/p> <label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Complianz para cookie consent management. <a href=\"https:\/\/cookiedatabase.org\/service\/complianz\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Estos datos no se comparten con terceros.&nbsp;Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\" target=\"_blank\" rel=\"noopener noreferrer\">pol\u00edtica de privacidad de Complianz<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_cookie_data\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">cmplz_cookie_data<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">365 d\u00edas<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Store information about cookies that have been detected on the site<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_rt_policy_id\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">cmplz_rt_policy_id<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">365 d\u00edas<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar la ID de la pol\u00edtica de cookies aceptada<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Automattic<\/h3> <p>Estad\u00edsticas<\/p> <label for=\"cmplz_service_automattic\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service automattic<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Automattic para website development. <a href=\"https:\/\/cookiedatabase.org\/service\/automattic\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/automattic.com\/cookies\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de Automattic<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/automattic\/tk_qs\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">tk_qs<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">30 minutos<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar funcionalidad entre p\u00e1ginas<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>GDPR Cookie Consent<\/h3> <p>Funcional<\/p> <label for=\"cmplz_service_gdpr-cookie-consent\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service gdpr-cookie-consent<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos GDPR Cookie Consent para cookie consent management. <a href=\"https:\/\/cookiedatabase.org\/service\/gdpr-cookie-consent\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Estos datos no se comparten con terceros.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/gdpr-cookie-consent\/viewed_cookie_policy\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">viewed_cookie_policy<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar si un mensaje ha sido mostrado<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Burst Statistics<\/h3> <p>Estad\u00edsticas (an\u00f3nimas)<\/p> <label for=\"cmplz_service_burst-statistics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service burst-statistics<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Burst Statistics para website statistics. <a href=\"https:\/\/cookiedatabase.org\/service\/burst-statistics\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Estos datos no se comparten con terceros.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Estad\u00edsticas (an\u00f3nimas)<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/burst-statistics\/burst_uid\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">burst_uid<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 mes<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Store and track interaction<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>TikTok<\/h3> <p>Marketing\/Seguimiento, Funcional<\/p> <label for=\"cmplz_service_tiktok\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service tiktok<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos TikTok para video display. <a href=\"https:\/\/cookiedatabase.org\/service\/tiktok\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/www.tiktok.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de TikTok<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Marketing\/Seguimiento<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/s_v_web_id\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">s_v_web_id<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/auto-draft-10\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">MONITOR_WEB_ID<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">3 meses<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/tt_webid\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">tt_webid<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 a\u00f1o<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/tt_webid_v2\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">tt_webid_v2<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 a\u00f1o<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/ttwid\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">ttwid<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 a\u00f1o<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_launch_mode\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp_launch_mode<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_session_id\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp_session_id<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacena una ID de sesi\u00f3n \u00fanica<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp-session-referer\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp-session-referer<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar el sitio web de referencia<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_tiktok_privious\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp_tiktok_privious<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp_extra_data\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp_extra_data<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar funcionalidad entre p\u00e1ginas<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/auto-draft-7\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp_original_traffic_type<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/guide-login-config\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">guide-login-config<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar un ID de usuario \u00fanico<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/__tea_cache_tokens_\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">__tea_cache_tokens_*<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacena una ID de sesi\u00f3n \u00fanica<\/div>      <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/csrf_session_id\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">csrf_session_id<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar protecci\u00f3n contra los piratas inform\u00e1ticos<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/auto-draft-9\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">tt_csrf_token<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar protecci\u00f3n contra los piratas inform\u00e1ticos<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/_abck\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">_abck<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 a\u00f1o<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar protecci\u00f3n contra los piratas inform\u00e1ticos<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp-newuser\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp-newuser<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar primera visita al sitio web<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/autoplay-config\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">autoplay-config<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar la configuraci\u00f3n<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/webapp-video-mute\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">webapp-video-mute<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar la configuraci\u00f3n<\/div>      <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/__tea_cache_first_\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">__tea_cache_first_*<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/tiktok\/f\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">f<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <\/div> <\/div><\/div><\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Google Fonts<\/h3> <p>Marketing\/Seguimiento<\/p> <label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Google Fonts para display of webfonts. <a href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de Google Fonts<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Marketing\/Seguimiento<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Google Fonts API<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">nada<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Solicitar la direcci\u00f3n IP del usuario<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>YouTube<\/h3> <p>Marketing\/Seguimiento, Funcional<\/p> <label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos YouTube para video display. <a href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de YouTube<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Marketing\/Seguimiento<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/gps\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">GPS<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar datos de ubicaci\u00f3n<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">YSC<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Store and track interaction<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">PREF<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">8 meses<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar las preferencias de los usuarios<\/div>      <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/visitor_info1_live\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">VISITOR_INFO1_LIVE<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">6 meses<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Estimar el ancho de banda<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Facebook<\/h3> <p>Marketing\/Seguimiento, Funcional<\/p> <label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service facebook<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Facebook para display of recent social posts and\/or social share buttons. <a href=\"https:\/\/cookiedatabase.org\/service\/facebook\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/www.facebook.com\/policy\/cookies\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de Facebook<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Marketing\/Seguimiento<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbc\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">_fbc<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">2 a\u00f1os<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar la \u00faltima visita<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fbm_\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">fbm*<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 a\u00f1o<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar detalles de la cuenta<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/xs\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">xs<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">3 meses<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacena una ID de sesi\u00f3n \u00fanica<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">fr<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">3 meses<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Habilitar la publicaci\u00f3n de anuncios o retargeting<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/act\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">act<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">90 d\u00edas<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Mantener los usuarios logeados<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbp\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">_fbp<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">3 meses<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar y realizar un seguimiento de las visitas a trav\u00e9s de m\u00faltiples sitios web<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/datr\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">datr<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">2 a\u00f1os<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar prevenci\u00f3n de fraude<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/c_user\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">c_user<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">30 d\u00edas<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar un ID de usuario \u00fanico<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/sb\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">sb<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">2 a\u00f1os<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar detalles del navegador<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbm_\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">*_fbm_<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 a\u00f1o<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar detalles de la cuenta<\/div>      <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/wd\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">wd<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 semana<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Determinar la resoluci\u00f3n de pantalla<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/csm\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">csm<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">90 d\u00edas<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Proporcionar prevenci\u00f3n de fraude<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/actppresence\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">actppresence<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar y rastrear si la pesta\u00f1a del navegador est\u00e1 activa<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Twitter<\/h3> <p>Funcional, Marketing\/Seguimiento<\/p> <label for=\"cmplz_service_twitter\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service twitter<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Twitter para display of recent social posts and\/or social share buttons. <a href=\"https:\/\/cookiedatabase.org\/service\/twitter\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/twitter.com\/en\/privacy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de Twitter<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/twitter\/local_storage_support_test\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">local_storage_support_test<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Cargar la funcionalidad de equilibrio de carga<\/div>      <div class=\"purpose\"><h4>Marketing\/Seguimiento<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/twitter\/metrics_token\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">metrics_token<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">persistente<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Almacenar si el usuario ha visto contenido incrustado<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>WhatsApp<\/h3> <p>Funcional<\/p> <label for=\"cmplz_service_whatsapp\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service whatsapp<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos WhatsApp para chat support. <a href=\"https:\/\/cookiedatabase.org\/service\/whatsapp\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/www.whatsapp.com\/legal\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de WhatsApp<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Funcional<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/whatsapp\/wa_lang_pref\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">wa_lang_pref<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">6 d\u00edas<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Guardar configuraciones de lenguaje<\/div> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/whatsapp\/wa_ul\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">wa_ul<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">sesi\u00f3n<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Provide access<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Instagram<\/h3> <p>Marketing\/Seguimiento<\/p> <label for=\"cmplz_service_instagram\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service instagram<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4> <p>Usamos Instagram para display of recent social posts and\/or social share buttons. <a href=\"https:\/\/cookiedatabase.org\/service\/instagram\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Leer m\u00e1s<\/a><\/p> <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a href=\"https:\/\/privacycenter.instagram.com\/policy\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">pol\u00edtica de privacidad de Instagram<\/a>.<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Marketing\/Seguimiento<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/instagram\/actppresence-2\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">actppresence<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">1 a\u00f1o<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\">Administrar la frecuencia de visualizaci\u00f3n de anuncios<\/div> <\/div> <\/details> <details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \"> <summary class=\"cmplz-service-header\"><div> <h3>Varios<\/h3> <p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p> <label for=\"cmplz_service_varios\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varios<\/span><\/label> <\/div> <\/summary> <div class=\"cmplz-service-description\"> <h4>Uso<\/h4>  <\/div> <div class=\"cmplz-sharing-data\"> <h4>Compartir datos<\/h4> <p>El intercambio de datos est\u00e1 pendiente de investigaci\u00f3n<\/p> <\/div> <div class=\"cookies-per-purpose\">     <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>     <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\">omWpApi<\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\"> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wp_preferences_user_\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">WP_PREFERENCES_USER_*<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\"> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\">omScrollHeight<\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\"> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\"><a href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/cookielawinfo-checkbox\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">cookielawinfo-checkbox-*<\/a><\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\"> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\">cmplz_consenttype<\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\">365 d\u00edas<\/div> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\">friends_with_mate<\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\"> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\">jetpack_sso_nonce<\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\"> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <div class=\"name-header\"> <h5>Nombre<\/h5> <\/div> <div class=\"name\">jetpack_sso_original_request<\/div> <div class=\"retention-header\"> <h5>Caducidad<\/h5> <\/div> <div class=\"retention\"> <div class=\"function-header\"> <h5>Funci\u00f3n<\/h5> <\/div> <div class=\"function\"> <\/div> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/details><\/div><\/div>\n\n\n<h4 class=\"wp-block-heading\">6. Consentiment<\/h4>\n\n\n\n<p style=\"text-align:justify\">Quan visite LA WEB per primera volta, li mostrarem una finestra emergent en una explicaci\u00f3 sobre les cookies. Tan pronte com fa\u00e7a clic en \u00abGuardar prefer\u00e8ncies\u00bb, accepta que usem les categories de cookies i plugins que ha seleccionat en la finestra emergent, tal i com es descriu en esta pol\u00edtica de cookies. Pot desactivar l&#8217;us de cookies a trav\u00e9s del seu navegador, pero, per favor, tinga en conte que LA WEB pot deixar de funcionar correctament.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">6.1. Gestione els seus ajustes de consentiment<\/h5>\n\n\n\n<p style=\"text-align:justify\">Ha carregat la pol\u00edtica de cookies sense compatibilitat en JavaScript. En AMP, pot utilisar el bot\u00f3 de gestionar el consentiment en la part inferior de la p\u00e0gina.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">7. Activaci\u00f3\/Desactivaci\u00f3 i eliminaci\u00f3 de cookies<\/h4>\n\n\n\n<p style=\"text-align:justify\">Pot utilisar el seu navegador d&#8217;Internet per a eliminar les cookies de forma autom\u00e0tica o manual. Tamb\u00e9 pot especificar que certes cookies no poden ser colocades. Una atra opci\u00f3 \u00e9s canviar els ajusts del seu navegador d&#8217;Internet per a que reba un mensage cada volta que es coloca una cookie. Per a obtindre m\u00e9s informaci\u00f3 sobre estes opcions, consulte les instruccions de la secci\u00f3 \u00abAjuda\u00bb del seu navegador.<br><br>Tingues en conte que LA WEB pot no funcionar correctament si totes les cookies estan desactivades. Si borra les cookies del seu navegador, es tornaran a colocar despuix del seu consentiment quan torne a visitar LA WEB.<\/p>\n\n\n\n<p style=\"text-align:justify\">En els seg\u00fcents enlla\u00e7os trobar\u00e0s instruccions per a habilitar o deshabilitar les cookies en els navegadors m\u00e9s comuns.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Explorer<\/strong><br><a href=\"https:\/\/support.microsoft.com\/es-es\/help\/17442\">https:\/\/support.microsoft.com\/es-es\/help\/17442<\/a><\/li>\n\n\n\n<li><strong>Firefox<\/strong><br><a href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\">http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-web<\/a><\/li>\n\n\n\n<li><strong>Google Chrome<\/strong><br><a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=es\">https:\/\/support.google.com\/chrome\/answer\/95647?hl=es<\/a><\/li>\n\n\n\n<li><strong>Safari<\/strong><br><a href=\"http:\/\/support.apple.com\/kb\/HT1677?viewlocale=es_ES\">http:\/\/support.apple.com\/kb\/HT1677?viewlocale=es_ES<\/a><\/li>\n\n\n\n<li><strong>Opera<\/strong><br><a href=\"http:\/\/help.opera.com\/Windows\/11.50\/es-ES\/cookies.html\">http:\/\/help.opera.com\/Windows\/11.50\/es-ES\/cookies.html<\/a><\/li>\n\n\n\n<li><strong>Atres Navegadors<\/strong><br>Consulte la documentaci\u00f3 del navegador que tinga instalat.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">8. Els teus drets sobre les senyes personals.<\/h4>\n\n\n\n<p>Tens els seg\u00fcents drets sobre les teues senyes personals:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>T\u00e9 dret a saber per qu\u00e9 es necessiten les teues senyes personals, qu\u00e9 succeir\u00e0 en elles i durant quant&nbsp;temps&nbsp;es conservaran.&nbsp;<\/li>\n\n\n\n<li><strong>Dret d&#8217;acc\u00e9s:<\/strong> tens dret a accedir a les teues senyes personals que coneixem.<\/li>\n\n\n\n<li><strong>Dret de rectificaci\u00f3:<\/strong> tens dret a completar, rectificar, borrar o bloquejar les teues senyes personals quan ho desiges.<\/li>\n\n\n\n<li>Si nos dones el teu consentiment per a processar les teues senyes, tens dret a revocar dit consentiment i a que s&#8217;eliminen les teues senyes personals.&nbsp;<\/li>\n\n\n\n<li><strong>Dret de cessi\u00f3 de les teues senyes:<\/strong> tens dret a solicitar totes les teues senyes personals al responsable del tractament i a transferir-los \u00edntegrament a un atre responsable del tractament.<\/li>\n\n\n\n<li><strong>Dret d&#8217;oposici\u00f3:<\/strong> pots opondre&#8217;t al tractament de les teues senyes. Nosatres complim en a\u00e7\u00f2, a menos que existixquen motius justificats per al processament.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Per a eixercir estos drets, per favor, contacta en nosatres. Per favor, consulta els detalls de contacte en la&nbsp;part&nbsp;inferior d&#8217;esta pol\u00edtica de cookies. Si tens alguna queixa sobre c\u00f3m gestionem les teues senyes, nos agradaria que nos la feres saber, pero tamb\u00e9 tens dret a enviar una queixa a l&#8217;autoritat supervisora (l&#8217;autoritat de protecci\u00f3 de senyes).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">9. Contacte<\/h4>\n\n\n\n<p style=\"text-align:justify\">Per a preguntes i\/o comentaris sobre la nostra pol\u00edtica de cookies i esta declaraci\u00f3, per favor, contacta en nosatros usant les seg\u00fcents senyes de contacte:<br>\nAGRUPACI\u00d3 EL PILAR SANT FRANCESC\n<br><a href=\"https:\/\/pilarsantfrancesc.es\">https:\/\/pilarsantfrancesc.es\/val\/wp-content\/uploads\/sites\/2\/2026\/02\/Triador-scaled-1.jpg<\/a>\n<br><a href=\"mailto:presidencia@pilarsantfrancesc.es\">presidencia@pilarsantfrancesc.es.<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En compliment en lo dispost en l&#8217;art\u00edcul 22.2 de la Llei 34\/2002, d&#8217;11 de juliol, de Servicis de la Societat de l&#8217;Informaci\u00f3 i de Comer\u00e7 Electr\u00f2nic, L&#8217;AGRUPACI\u00d3 EL PILAR SANT FRANCESC (en avant, el &#8220;TITULAR&#8221;), l&#8217;informa de que pot recopilar informaci\u00f3 sobre els h\u00e0bits de b\u00fasqueda dels usuaris de la web per mig de cookies [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-511","page","type-page","status-publish","hentry"],"aioseo_notices":[],"jetpack-related-posts":[{"id":507,"url":"https:\/\/pilarsantfrancesc.es\/val\/politica-privacitat\/","url_meta":{"origin":511,"position":0},"title":"Pol\u00edtica de privacitat","author":"imacuchc","date":"4 Juny, 2019","format":false,"excerpt":"L'Agrupaci\u00f3 El Pilar Sant Francesc (en avant, el \"TITULAR\"), t'informa sobre la seua Pol\u00edtica de Privacitat respecte al tractament i protecci\u00f3 de les senyes de car\u00e0cter personal dels usuaris i clients que puguen ser recaptats per la navegaci\u00f3 o contrataci\u00f3 de servicis a trav\u00e9s del lloc web https:\/\/pilarsantfrancesc.es\/val (en avant,\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":445,"url":"https:\/\/pilarsantfrancesc.es\/val\/avis-llegal\/","url_meta":{"origin":511,"position":1},"title":"Av\u00eds Llegal","author":"imacuchc","date":"27 Maig, 2019","format":false,"excerpt":"1. IDENTIFICACI\u00d3 I TITULARITAT En compliment en el deure d'informaci\u00f3 arreplegat en l'art\u00edcul 10 de la Llei 34\/2002, d'11 de juliol, de Servicis de la Societat de l'Informaci\u00f3 i del Comer\u00e7 Electr\u00f2nic (LSSI), el TITULAR expon les seues senyes identificatives: Titular:AGRUPACI\u00d3 EL PILAR SANT FRANCESC. CIF:G46896916. Inscripci\u00f3 Registre Nacional i\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":384,"url":"https:\/\/pilarsantfrancesc.es\/val\/contacte\/","url_meta":{"origin":511,"position":2},"title":"Contacte","author":"imacuchc","date":"26 Maig, 2019","format":false,"excerpt":"Estos s\u00f3n els correus electr\u00f2nics de l'Agrupaci\u00f3 i del Sector. Si vols posar-te en contacte en el president, secretaria, mijos de comunicaci\u00f3, tesoreria, delegats del sector o inscriure't en els Campeonats, solament tens que fer clic sobre la direcci\u00f3 i enviar-nos un correu electr\u00f2nic. Presid\u00e8ncia: presidencia@pilarsantfrancesc.es Secretaria: secretaria@pilarsantfrancesc.es Tesoreria: tesoreria@pilarsantfrancesc.es\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"Image Correu Electr\u00f2nic","src":"https:\/\/i0.wp.com\/pilarsantfrancesc.es\/val\/wp-content\/uploads\/sites\/2\/2023\/12\/correu-electronic.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10867,"url":"https:\/\/pilarsantfrancesc.es\/val\/millors-ninots-seccio-indultats-aepsf\/","url_meta":{"origin":511,"position":3},"title":"Millors Ninots de Secci\u00f3 i Indultats de l&#8217;AEPSF","author":"imacuchc","date":"17 Setembre, 2023","format":false,"excerpt":"De l'any 2025 a 1992 Any 2025 Ninot Infantil Premi al Ninot Infantil en m\u00e9s Ingeni i Gr\u00e0cia Falla Quart i PalomarArtiste: Rub\u00e9n CanetLema: BUTR\u00cdCIA. La princesa que detestava l'higiene.Secci\u00f3: Novena Ninots Grans Premi al Millor Ninot de Secci\u00f3 Tamb\u00e9 guanya el Premi al ninot en m\u00e9s Ingeni i Gr\u00e1ciaFalla\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/pilarsantfrancesc.es\/val\/wp-content\/uploads\/sites\/2\/2023\/09\/ninot25_196g.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/pilarsantfrancesc.es\/val\/wp-content\/uploads\/sites\/2\/2023\/09\/ninot25_196g.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/pilarsantfrancesc.es\/val\/wp-content\/uploads\/sites\/2\/2023\/09\/ninot25_196g.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":567,"url":"https:\/\/pilarsantfrancesc.es\/val\/calendariaepsf\/","url_meta":{"origin":511,"position":4},"title":"Calendari d&#8217;Actes","author":"imacuchc","date":"5 Juny, 2019","format":false,"excerpt":"Ac\u00ed pots vore tots els actes que l'Agrupaci\u00f3 t\u00e9 prevists realisar durant tot l'eixercici faller.Inclou tamb\u00e9 les presentacions de les 12 falles de l'Agrupaci\u00f3.Si hi ha algun canvi de data, hora o lloc, s'avisar\u00e0 en la suficient antelaci\u00f3. Calendari de l'Agrupaci\u00f3 EPSF Si vols imprimir un llistat dels actes de\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"icono-eventos","src":"https:\/\/i0.wp.com\/pilarsantfrancesc.es\/val\/wp-content\/uploads\/sites\/2\/2019\/11\/icono-calendario.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12116,"url":"https:\/\/pilarsantfrancesc.es\/val\/esbossos\/any-2024\/","url_meta":{"origin":511,"position":5},"title":"Any 2024","author":"imacuchc","date":"30 Novembre, 2023","format":false,"excerpt":"Ac\u00ed teniu els esbossos que es varen presentar en la nostra Agrupaci\u00f3 el 26 de novembre de 2023 en la XII Presentaci\u00f3 d\u2019Esbossos de l\u2019Agrupaci\u00f3 i que se plantaran en les nostres demarcacions del 15 al 19 de mar\u00e7 de 2024. Les fotografies pujades de les Falles s\u00f3n de Cendra\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/pages\/511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/comments?post=511"}],"version-history":[{"count":1,"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/pages\/511\/revisions"}],"predecessor-version":[{"id":10528,"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/pages\/511\/revisions\/10528"}],"wp:attachment":[{"href":"https:\/\/pilarsantfrancesc.es\/val\/wp-json\/wp\/v2\/media?parent=511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}